{"id":1504,"date":"2024-02-02T15:20:30","date_gmt":"2024-02-02T14:20:30","guid":{"rendered":"https:\/\/museedujeu.ch\/activite\/geburtstage\/"},"modified":"2026-02-12T17:50:35","modified_gmt":"2026-02-12T16:50:35","slug":"geburtstage","status":"publish","type":"activity","link":"https:\/\/museedujeu.ch\/de\/activite\/geburtstage\/","title":{"rendered":"Geburtstage"},"content":{"rendered":"\n<p>Feiern Sie Ihren Geburtstag im MSJ mit Ihren Freunden! Entdecken, lernen und spielen Sie eine Vielzahl von verschiedenen Spielen.  <\/p>\n\n<p><strong>Auf dem Programm steht eine kurze F\u00fchrung, gefolgt von einem spielerischen Workshop unter der Leitung eines Fremdenf\u00fchrers.<\/strong><\/p>\n\n<p>Die Aktivit\u00e4t beginnt mittwochs um 14.00 Uhr und samstags und sonntags um 10.00 oder 14.00 Uhr.<\/p>\n\n<hr class=\"wp-block-separator has-text-color has-white-color has-alpha-channel-opacity has-white-background-color has-background is-style-dots\"\/>\n\n<p>Sie haben die Wahl zwischen den folgenden Themen:<\/p>\n\n<h5 class=\"wp-block-heading\"><strong>Tiermasken (5 bis 7 Jahre)<\/strong><\/h5>\n\n<p>Gehen Sie in den Etagen des Museums auf Tierjagd und lassen Sie dann Ihre Fantasie spielen, um Ihre Tiermaske zu dekorieren und sich eine wunderbare Welt zu erfinden.<\/p>\n\n<p><strong>Tarif<\/strong>: CHF 190.*.<\/p>\n\n<hr class=\"wp-block-separator has-text-color has-white-color has-alpha-channel-opacity has-white-background-color has-background is-style-dots\"\/>\n\n<h5 class=\"wp-block-heading\"><strong>Der Fall ist in der Tasche! (7 bis 9 Jahre)<\/strong><\/h5>\n\n<p>Eine Tasche, die als Spielbrett dient? Ja!  Nachdem Sie verschiedene Arten von Spielen im Museum entdeckt haben, entwerfen und dekorieren Sie Ihre eigenen Spiele wie r\u00f6misches Marello, Taquin und Tic-Tac-Toe. Treten Sie dann mit Ihren Freunden in wilden Partien gegeneinander an, die in einem menschlichen Mischmasch enden.<\/p>\n\n<p><strong>Tarif<\/strong>: CHF 190.- **.<\/p>\n\n<hr class=\"wp-block-separator has-text-color has-white-color has-alpha-channel-opacity has-white-background-color has-background is-style-dots\"\/>\n\n<h5 class=\"wp-block-heading\"><strong>\u00dcberraschung des Tages (8 bis 12 Jahre)<\/strong><\/h5>\n\n<p>Vertrauen Sie unseren F\u00fchrern, die Ihnen nach einem Rundgang durch die Ausstellungen des Museums verschiedene Spiele nach ihren W\u00fcnschen oder Vorlieben zeigen werden.<\/p>\n\n<p><strong>Tarif<\/strong>: CHF 190.- **.<\/p>\n\n<hr class=\"wp-block-separator has-text-color has-white-color has-alpha-channel-opacity has-white-background-color has-background is-style-dots\"\/>\n\n<p>Am Ende der Aktivit\u00e4t (1,5 Stunden) bietet das Museum Ihnen an, f\u00fcr eine Stunde im Animationsraum zu bleiben, um eine Geburtstagsparty zu veranstalten. Der Kuchen, die Getr\u00e4nke und das Service m\u00fcssen von Ihren Eltern mitgebracht werden. <\/p>\n\n<hr class=\"wp-block-separator has-text-color has-white-color has-alpha-channel-opacity has-white-background-color has-background\"\/>\n\n<p><em>Kinder stehen unter der st\u00e4ndigen Verantwortung eines Erwachsenen.<\/em><\/p>\n\n<p class=\"has-small-font-size\">*  <em>Pauschalpreis f\u00fcr maximal 8 Kinder und 2 Erwachsene. F\u00fcr jedes weitere Kind wird ein Zuschlag von CHF 20 berechnet. Ab 10 Kindern wird ein zweiter F\u00fchrer hinzugezogen und CHF 100.00 f\u00fcr maximal 16 Kinder berechnet.  <\/em><\/p>\n\n<p class=\"has-small-font-size\">**  <em>Pauschalpreis f\u00fcr maximal 12 Kinder und 2 Erwachsene. F\u00fcr jedes weitere Kind wird ein Zuschlag von CHF 20 berechnet. Ab 14 Kindern wird ein zweiter F\u00fchrer hinzugezogen und CHF 100.00 f\u00fcr maximal 16 Kinder berechnet.  <\/em><\/p>\n","protected":false},"template":"","class_list":["post-1504","activity","type-activity","status-publish","hentry"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.4 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Geburtstage | Mus\u00e9e Suisse du Jeu<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/museedujeu.ch\/de\/activite\/geburtstage\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Geburtstage | Mus\u00e9e Suisse du Jeu\" \/>\n<meta property=\"og:description\" content=\"Feiern Sie Ihren Geburtstag im MSJ mit Ihren Freunden! Entdecken, lernen und spielen Sie eine Vielzahl von verschiedenen Spielen. Auf dem Programm steht eine kurze F\u00fchrung, gefolgt von einem spielerischen Workshop unter der Leitung eines Fremdenf\u00fchrers. Die Aktivit\u00e4t beginnt mittwochs um 14.00 Uhr und samstags und sonntags um 10.00 oder 14.00 Uhr. Sie haben die [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/museedujeu.ch\/de\/activite\/geburtstage\/\" \/>\n<meta property=\"og:site_name\" content=\"Mus\u00e9e Suisse du Jeu\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/museesuissedujeu\" \/>\n<meta property=\"article:modified_time\" content=\"2026-02-12T16:50:35+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/museedujeu.ch\/wp-content\/uploads\/2024\/02\/frame-1..jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"2400\" \/>\n\t<meta property=\"og:image:height\" content=\"1350\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Gesch\u00e4tzte Lesezeit\" \/>\n\t<meta name=\"twitter:data1\" content=\"1\u00a0Minute\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/museedujeu.ch\\\/de\\\/activite\\\/geburtstage\\\/\",\"url\":\"https:\\\/\\\/museedujeu.ch\\\/de\\\/activite\\\/geburtstage\\\/\",\"name\":\"Geburtstage | Mus\u00e9e Suisse du Jeu\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/museedujeu.ch\\\/de\\\/#website\"},\"datePublished\":\"2024-02-02T14:20:30+00:00\",\"dateModified\":\"2026-02-12T16:50:35+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/museedujeu.ch\\\/de\\\/activite\\\/geburtstage\\\/#breadcrumb\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/museedujeu.ch\\\/de\\\/activite\\\/geburtstage\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/museedujeu.ch\\\/de\\\/activite\\\/geburtstage\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\\\/\\\/museedujeu.ch\\\/de\\\/startseite\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Activit\u00e9s\",\"item\":\"https:\\\/\\\/museedujeu.ch\\\/de\\\/activite\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Geburtstage\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/museedujeu.ch\\\/de\\\/#website\",\"url\":\"https:\\\/\\\/museedujeu.ch\\\/de\\\/\",\"name\":\"Mus\u00e9e Suisse du jeu\",\"description\":\"Voyage ludique et fascinant dans le monde des jeux\",\"publisher\":{\"@id\":\"https:\\\/\\\/museedujeu.ch\\\/de\\\/#organization\"},\"alternateName\":\"MSJ\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/museedujeu.ch\\\/de\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/museedujeu.ch\\\/de\\\/#organization\",\"name\":\"Mus\u00e9e Suisse du jeu\",\"alternateName\":\"MSJ\",\"url\":\"https:\\\/\\\/museedujeu.ch\\\/de\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/museedujeu.ch\\\/de\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/museedujeu.321dev.ch\\\/wp-content\\\/uploads\\\/2024\\\/01\\\/favicon..png\",\"contentUrl\":\"https:\\\/\\\/museedujeu.321dev.ch\\\/wp-content\\\/uploads\\\/2024\\\/01\\\/favicon..png\",\"width\":512,\"height\":512,\"caption\":\"Mus\u00e9e Suisse du jeu\"},\"image\":{\"@id\":\"https:\\\/\\\/museedujeu.ch\\\/de\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/museesuissedujeu\",\"https:\\\/\\\/www.instagram.com\\\/museesuissedujeu\\\/\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Geburtstage | Mus\u00e9e Suisse du Jeu","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/museedujeu.ch\/de\/activite\/geburtstage\/","og_locale":"de_DE","og_type":"article","og_title":"Geburtstage | Mus\u00e9e Suisse du Jeu","og_description":"Feiern Sie Ihren Geburtstag im MSJ mit Ihren Freunden! Entdecken, lernen und spielen Sie eine Vielzahl von verschiedenen Spielen. Auf dem Programm steht eine kurze F\u00fchrung, gefolgt von einem spielerischen Workshop unter der Leitung eines Fremdenf\u00fchrers. Die Aktivit\u00e4t beginnt mittwochs um 14.00 Uhr und samstags und sonntags um 10.00 oder 14.00 Uhr. Sie haben die [&hellip;]","og_url":"https:\/\/museedujeu.ch\/de\/activite\/geburtstage\/","og_site_name":"Mus\u00e9e Suisse du Jeu","article_publisher":"https:\/\/www.facebook.com\/museesuissedujeu","article_modified_time":"2026-02-12T16:50:35+00:00","og_image":[{"width":2400,"height":1350,"url":"https:\/\/museedujeu.ch\/wp-content\/uploads\/2024\/02\/frame-1..jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_misc":{"Gesch\u00e4tzte Lesezeit":"1\u00a0Minute"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/museedujeu.ch\/de\/activite\/geburtstage\/","url":"https:\/\/museedujeu.ch\/de\/activite\/geburtstage\/","name":"Geburtstage | Mus\u00e9e Suisse du Jeu","isPartOf":{"@id":"https:\/\/museedujeu.ch\/de\/#website"},"datePublished":"2024-02-02T14:20:30+00:00","dateModified":"2026-02-12T16:50:35+00:00","breadcrumb":{"@id":"https:\/\/museedujeu.ch\/de\/activite\/geburtstage\/#breadcrumb"},"inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["https:\/\/museedujeu.ch\/de\/activite\/geburtstage\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/museedujeu.ch\/de\/activite\/geburtstage\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/museedujeu.ch\/de\/startseite\/"},{"@type":"ListItem","position":2,"name":"Activit\u00e9s","item":"https:\/\/museedujeu.ch\/de\/activite\/"},{"@type":"ListItem","position":3,"name":"Geburtstage"}]},{"@type":"WebSite","@id":"https:\/\/museedujeu.ch\/de\/#website","url":"https:\/\/museedujeu.ch\/de\/","name":"Mus\u00e9e Suisse du jeu","description":"Voyage ludique et fascinant dans le monde des jeux","publisher":{"@id":"https:\/\/museedujeu.ch\/de\/#organization"},"alternateName":"MSJ","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/museedujeu.ch\/de\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de"},{"@type":"Organization","@id":"https:\/\/museedujeu.ch\/de\/#organization","name":"Mus\u00e9e Suisse du jeu","alternateName":"MSJ","url":"https:\/\/museedujeu.ch\/de\/","logo":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/museedujeu.ch\/de\/#\/schema\/logo\/image\/","url":"https:\/\/museedujeu.321dev.ch\/wp-content\/uploads\/2024\/01\/favicon..png","contentUrl":"https:\/\/museedujeu.321dev.ch\/wp-content\/uploads\/2024\/01\/favicon..png","width":512,"height":512,"caption":"Mus\u00e9e Suisse du jeu"},"image":{"@id":"https:\/\/museedujeu.ch\/de\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/museesuissedujeu","https:\/\/www.instagram.com\/museesuissedujeu\/"]}]}},"_links":{"self":[{"href":"https:\/\/museedujeu.ch\/de\/wp-json\/wp\/v2\/activity\/1504","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/museedujeu.ch\/de\/wp-json\/wp\/v2\/activity"}],"about":[{"href":"https:\/\/museedujeu.ch\/de\/wp-json\/wp\/v2\/types\/activity"}],"wp:attachment":[{"href":"https:\/\/museedujeu.ch\/de\/wp-json\/wp\/v2\/media?parent=1504"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}